{"id":1594,"date":"2025-04-11T10:35:22","date_gmt":"2025-04-11T13:35:22","guid":{"rendered":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/?page_id=1594"},"modified":"2025-04-24T10:47:19","modified_gmt":"2025-04-24T13:47:19","slug":"spins-offs","status":"publish","type":"page","link":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/","title":{"rendered":"Spin Offs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1594\" class=\"elementor elementor-1594\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a686319 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a686319\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2153e8\" data-id=\"b2153e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4c7d4e elementor-widget elementor-widget-html\" data-id=\"b4c7d4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uc-title panel-widget-style\"><div>\r\n<div class=\"siteorigin-widget-tinymce textwidget\">\r\n\t<h3>Spin-Offs<\/h3>\r\n<\/div>\r\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7929dc elementor-widget elementor-widget-text-editor\" data-id=\"b7929dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Departamento de Ingenier\u00eda Industrial y Sistemas ha desarrollado un potente foco de transferencia tecnol\u00f3gica, innovaci\u00f3n y emprendimiento, lo cual se ha logrado mediante la integraci\u00f3n de la investigaci\u00f3n a la transferencia, a trav\u00e9s de la gesti\u00f3n \u00e1gil y eficiente del conocimiento.<\/p><p>Los proyectos y spin-offs dirigidos y desarrollados por los profesores del DIIS est\u00e1n relacionados con diversos t\u00f3picos relevantes para la sociedad y el mundo actual. A trav\u00e9s del apoyo a pol\u00edticas p\u00fablicas y sociales pueden complementar, potenciar y solucionar problem\u00e1ticas urgentes que se deben mitigar como pa\u00eds.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956b6a8 wpr-advanced-accordion-icon-side-box elementor-widget elementor-widget-wpr-advanced-accordion\" data-id=\"956b6a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;active_item&quot;:1}\" data-widget_type=\"wpr-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"wpr-advanced-accordion\" data-accordion-type=\"accordion\" data-active-index=\"1\" data-accordion-trigger=\"click\" data-interaction-speed=\"0.4\">\n\n\t\t\t\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-desktop\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">Pricing SpA<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>Pricing SpA, fundada por el profesor Juan Carlos Ferrer, desarrolla e implementa soluciones de Pricing &amp; Revenue Managment, mediante una metodolog\u00eda de trabajo basada en la construcci\u00f3n de modelos cuantitativos capaces de proyectar el comportamiento de los clientes para optimizar objetivos claves de negocio. Se han incorporado t\u00e9cnicas anal\u00edticas y sistem\u00e1ticas que entregan bases objetivas a la toma de decisiones, estandarizando y dando visibilidad a metodolog\u00edas para determinaciones claves del negocio. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, agroindustria, automotriz, servicios e inmobiliaria, etc.), constituy\u00e9ndose en spinoff de Dictuc S.A. el a\u00f1o 2014.<\/p><p>Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0<a href=\"http:\/\/www.pricing.cl\/\">http:\/\/www.pricing.cl\/<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-telegram-plane\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">Shift SpA<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>Shift SpA, fundada por los profesores Juan Carlos Ferrer y Juan Carlos Mu\u00f1oz, se especializa en la optimizaci\u00f3n de la fuerza laboral en Am\u00e9rica Latina, generando valor para sus clientes mediante una gesti\u00f3n m\u00e1s eficiente de la productividad laboral, compatibilizando un mejor nivel de servicio a clientes y calidad de vida para los empleados con menor inversi\u00f3n en personal. Esto es posible gracias a sus a\u00f1os de experiencia en consultor\u00eda, desarrollo e implementaci\u00f3n de soluciones integrales de administraci\u00f3n de la fuerza laboral, que cuentan con asesor\u00eda y soporte local para un efectivo y cercano acompa\u00f1amiento acorde a la realidad de cada empresa. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, salud, transporte, casinos de juego, hoteler\u00eda, plantas productivas y financieras), con presencia en Argentina, Per\u00fa, Brasil, Uruguay, Colombia y Chile. El a\u00f1o 2014 se constituy\u00f3 como spinoff de Dictuc S.A.<\/p><p>Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0<a href=\"http:\/\/www.shiftlabor.com\/\">http:\/\/www.shiftlabor.com\/<\/a><\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                \n\t\t\t\t\t<div class=\"wpr-accordion-item-wrap\">\n\t\t\t\t\t\t<button class=\"wpr-acc-button\">\n\t\t\t\t\t\t\t<span class=\"wpr-acc-item-title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-icon-box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-title-icon\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-layer-group\"><\/i>\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"wpr-acc-title-text\">Title #3<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-close\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t<span class=\"wpr-toggle-icon wpr-ti-open\"><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"wpr-acc-panel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wpr-acc-panel-content\"><p>Item content. Click the edit button to change this text.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n                    <\/div>\n\n                            <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9395795 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9395795\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-362a954\" data-id=\"362a954\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8c96245\" data-id=\"8c96245\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8494b47\" data-id=\"8494b47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c264039\" data-id=\"c264039\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Spin-Offs El Departamento de Ingenier\u00eda Industrial y Sistemas ha desarrollado un potente foco de transferencia tecnol\u00f3gica, innovaci\u00f3n y emprendimiento, lo cual se ha logrado mediante la integraci\u00f3n de la investigaci\u00f3n a la transferencia, a trav\u00e9s de la gesti\u00f3n \u00e1gil y eficiente del conocimiento. Los proyectos y spin-offs dirigidos y desarrollados por los profesores del DIIS est\u00e1n relacionados con diversos t\u00f3picos relevantes para la sociedad y el mundo actual. A trav\u00e9s del apoyo a pol\u00edticas p\u00fablicas y sociales pueden complementar, potenciar y solucionar problem\u00e1ticas urgentes que se deben mitigar como pa\u00eds. Pricing SpA Pricing SpA, fundada por el profesor Juan Carlos Ferrer, desarrolla e implementa soluciones de Pricing &amp; Revenue Managment, mediante una metodolog\u00eda de trabajo basada en la construcci\u00f3n de modelos cuantitativos capaces de proyectar el comportamiento de los clientes para optimizar objetivos claves de negocio. Se han incorporado t\u00e9cnicas anal\u00edticas y sistem\u00e1ticas que entregan bases objetivas a la toma de decisiones, estandarizando y dando visibilidad a metodolog\u00edas para determinaciones claves del negocio. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, agroindustria, automotriz, servicios e inmobiliaria, etc.), constituy\u00e9ndose en spinoff de Dictuc S.A. el a\u00f1o 2014. Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0http:\/\/www.pricing.cl\/ Shift SpA Shift SpA, fundada por los profesores Juan Carlos Ferrer y Juan Carlos Mu\u00f1oz, se especializa en la optimizaci\u00f3n de la fuerza laboral en Am\u00e9rica Latina, generando valor para sus clientes mediante una gesti\u00f3n m\u00e1s eficiente de la productividad laboral, compatibilizando un mejor nivel de servicio a clientes y calidad de vida para los empleados con menor inversi\u00f3n en personal. Esto es posible gracias a sus a\u00f1os de experiencia en consultor\u00eda, desarrollo e implementaci\u00f3n de soluciones integrales de administraci\u00f3n de la fuerza laboral, que cuentan con asesor\u00eda y soporte local para un efectivo y cercano acompa\u00f1amiento acorde a la realidad de cada empresa. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, salud, transporte, casinos de juego, hoteler\u00eda, plantas productivas y financieras), con presencia en Argentina, Per\u00fa, Brasil, Uruguay, Colombia y Chile. El a\u00f1o 2014 se constituy\u00f3 como spinoff de Dictuc S.A. Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0http:\/\/www.shiftlabor.com\/ Title #3 Item content. Click the edit button to change this text.<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":1592,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1594","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spin Offs - Departamento de Ingenier\u00eda Industrial y de Sistemas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spin Offs - Departamento de Ingenier\u00eda Industrial y de Sistemas\" \/>\n<meta property=\"og:description\" content=\"Spin-Offs El Departamento de Ingenier\u00eda Industrial y Sistemas ha desarrollado un potente foco de transferencia tecnol\u00f3gica, innovaci\u00f3n y emprendimiento, lo cual se ha logrado mediante la integraci\u00f3n de la investigaci\u00f3n a la transferencia, a trav\u00e9s de la gesti\u00f3n \u00e1gil y eficiente del conocimiento. Los proyectos y spin-offs dirigidos y desarrollados por los profesores del DIIS est\u00e1n relacionados con diversos t\u00f3picos relevantes para la sociedad y el mundo actual. A trav\u00e9s del apoyo a pol\u00edticas p\u00fablicas y sociales pueden complementar, potenciar y solucionar problem\u00e1ticas urgentes que se deben mitigar como pa\u00eds. Pricing SpA Pricing SpA, fundada por el profesor Juan Carlos Ferrer, desarrolla e implementa soluciones de Pricing &amp; Revenue Managment, mediante una metodolog\u00eda de trabajo basada en la construcci\u00f3n de modelos cuantitativos capaces de proyectar el comportamiento de los clientes para optimizar objetivos claves de negocio. Se han incorporado t\u00e9cnicas anal\u00edticas y sistem\u00e1ticas que entregan bases objetivas a la toma de decisiones, estandarizando y dando visibilidad a metodolog\u00edas para determinaciones claves del negocio. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, agroindustria, automotriz, servicios e inmobiliaria, etc.), constituy\u00e9ndose en spinoff de Dictuc S.A. el a\u00f1o 2014. Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0http:\/\/www.pricing.cl\/ Shift SpA Shift SpA, fundada por los profesores Juan Carlos Ferrer y Juan Carlos Mu\u00f1oz, se especializa en la optimizaci\u00f3n de la fuerza laboral en Am\u00e9rica Latina, generando valor para sus clientes mediante una gesti\u00f3n m\u00e1s eficiente de la productividad laboral, compatibilizando un mejor nivel de servicio a clientes y calidad de vida para los empleados con menor inversi\u00f3n en personal. Esto es posible gracias a sus a\u00f1os de experiencia en consultor\u00eda, desarrollo e implementaci\u00f3n de soluciones integrales de administraci\u00f3n de la fuerza laboral, que cuentan con asesor\u00eda y soporte local para un efectivo y cercano acompa\u00f1amiento acorde a la realidad de cada empresa. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, salud, transporte, casinos de juego, hoteler\u00eda, plantas productivas y financieras), con presencia en Argentina, Per\u00fa, Brasil, Uruguay, Colombia y Chile. El a\u00f1o 2014 se constituy\u00f3 como spinoff de Dictuc S.A. Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0http:\/\/www.shiftlabor.com\/ Title #3 Item content. Click the edit button to change this text.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Ingenier\u00eda Industrial y de Sistemas\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-24T13:47:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/vinculacion\\\/spins-offs\\\/\",\"url\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/vinculacion\\\/spins-offs\\\/\",\"name\":\"Spin Offs - Departamento de Ingenier\u00eda Industrial y de Sistemas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/#website\"},\"datePublished\":\"2025-04-11T13:35:22+00:00\",\"dateModified\":\"2025-04-24T13:47:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/vinculacion\\\/spins-offs\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/vinculacion\\\/spins-offs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/vinculacion\\\/spins-offs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinculaci\u00f3n\",\"item\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/vinculacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spin Offs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/#website\",\"url\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/\",\"name\":\"Departamento de Ingenier\u00eda Industrial y de Sistemas\",\"description\":\"Escuela de Ingenier\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/#organization\",\"name\":\"Departamento de Ingenier\u00eda Industrial y de Sistemas\",\"url\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-UC-P2727-01.png\",\"contentUrl\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-UC-P2727-01.png\",\"width\":307,\"height\":414,\"caption\":\"Departamento de Ingenier\u00eda Industrial y de Sistemas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ing.uc.cl\\\/industrial-y-sistemas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spin Offs - Departamento de Ingenier\u00eda Industrial y de Sistemas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/","og_locale":"es_ES","og_type":"article","og_title":"Spin Offs - Departamento de Ingenier\u00eda Industrial y de Sistemas","og_description":"Spin-Offs El Departamento de Ingenier\u00eda Industrial y Sistemas ha desarrollado un potente foco de transferencia tecnol\u00f3gica, innovaci\u00f3n y emprendimiento, lo cual se ha logrado mediante la integraci\u00f3n de la investigaci\u00f3n a la transferencia, a trav\u00e9s de la gesti\u00f3n \u00e1gil y eficiente del conocimiento. Los proyectos y spin-offs dirigidos y desarrollados por los profesores del DIIS est\u00e1n relacionados con diversos t\u00f3picos relevantes para la sociedad y el mundo actual. A trav\u00e9s del apoyo a pol\u00edticas p\u00fablicas y sociales pueden complementar, potenciar y solucionar problem\u00e1ticas urgentes que se deben mitigar como pa\u00eds. Pricing SpA Pricing SpA, fundada por el profesor Juan Carlos Ferrer, desarrolla e implementa soluciones de Pricing &amp; Revenue Managment, mediante una metodolog\u00eda de trabajo basada en la construcci\u00f3n de modelos cuantitativos capaces de proyectar el comportamiento de los clientes para optimizar objetivos claves de negocio. Se han incorporado t\u00e9cnicas anal\u00edticas y sistem\u00e1ticas que entregan bases objetivas a la toma de decisiones, estandarizando y dando visibilidad a metodolog\u00edas para determinaciones claves del negocio. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, agroindustria, automotriz, servicios e inmobiliaria, etc.), constituy\u00e9ndose en spinoff de Dictuc S.A. el a\u00f1o 2014. Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0http:\/\/www.pricing.cl\/ Shift SpA Shift SpA, fundada por los profesores Juan Carlos Ferrer y Juan Carlos Mu\u00f1oz, se especializa en la optimizaci\u00f3n de la fuerza laboral en Am\u00e9rica Latina, generando valor para sus clientes mediante una gesti\u00f3n m\u00e1s eficiente de la productividad laboral, compatibilizando un mejor nivel de servicio a clientes y calidad de vida para los empleados con menor inversi\u00f3n en personal. Esto es posible gracias a sus a\u00f1os de experiencia en consultor\u00eda, desarrollo e implementaci\u00f3n de soluciones integrales de administraci\u00f3n de la fuerza laboral, que cuentan con asesor\u00eda y soporte local para un efectivo y cercano acompa\u00f1amiento acorde a la realidad de cada empresa. Desde el a\u00f1o 2006 en que fue fundada ha acumulado experiencia en diversas industrias (retail, salud, transporte, casinos de juego, hoteler\u00eda, plantas productivas y financieras), con presencia en Argentina, Per\u00fa, Brasil, Uruguay, Colombia y Chile. El a\u00f1o 2014 se constituy\u00f3 como spinoff de Dictuc S.A. Para mayor informaci\u00f3n dirigirse al siguiente link:\u00a0http:\/\/www.shiftlabor.com\/ Title #3 Item content. Click the edit button to change this text.","og_url":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/","og_site_name":"Departamento de Ingenier\u00eda Industrial y de Sistemas","article_modified_time":"2025-04-24T13:47:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/","url":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/","name":"Spin Offs - Departamento de Ingenier\u00eda Industrial y de Sistemas","isPartOf":{"@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/#website"},"datePublished":"2025-04-11T13:35:22+00:00","dateModified":"2025-04-24T13:47:19+00:00","breadcrumb":{"@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/spins-offs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/"},{"@type":"ListItem","position":2,"name":"Vinculaci\u00f3n","item":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/vinculacion\/"},{"@type":"ListItem","position":3,"name":"Spin Offs"}]},{"@type":"WebSite","@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/#website","url":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/","name":"Departamento de Ingenier\u00eda Industrial y de Sistemas","description":"Escuela de Ingenier\u00eda","publisher":{"@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"},{"@type":"Organization","@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/#organization","name":"Departamento de Ingenier\u00eda Industrial y de Sistemas","url":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/","logo":{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/#\/schema\/logo\/image\/","url":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-content\/uploads\/2023\/11\/cropped-UC-P2727-01.png","contentUrl":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-content\/uploads\/2023\/11\/cropped-UC-P2727-01.png","width":307,"height":414,"caption":"Departamento de Ingenier\u00eda Industrial y de Sistemas"},"image":{"@id":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/#\/schema\/logo\/image\/"}}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Pipe Aliaga","author_link":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/author\/fealiaga\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"Spin-Offs El Departamento de Ingenier\u00eda Industrial y Sistemas ha desarrollado un potente foco de transferencia tecnol\u00f3gica, innovaci\u00f3n y emprendimiento, lo cual se ha logrado mediante la integraci\u00f3n de la investigaci\u00f3n a la transferencia, a trav\u00e9s de la gesti\u00f3n \u00e1gil y eficiente del conocimiento. Los proyectos y spin-offs dirigidos y desarrollados por los profesores del DIIS&hellip;","_links":{"self":[{"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/pages\/1594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/comments?post=1594"}],"version-history":[{"count":5,"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/pages\/1594\/revisions"}],"predecessor-version":[{"id":355416,"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/pages\/1594\/revisions\/355416"}],"up":[{"embeddable":true,"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/pages\/1592"}],"wp:attachment":[{"href":"https:\/\/www.ing.uc.cl\/industrial-y-sistemas\/wp-json\/wp\/v2\/media?parent=1594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}